{"id":5729,"date":"2022-04-16T09:50:37","date_gmt":"2022-04-16T09:50:37","guid":{"rendered":"https:\/\/classof2023.fountainheadschools.org\/?p=5729"},"modified":"2022-04-16T09:50:37","modified_gmt":"2022-04-16T09:50:37","slug":"2d-floor-planning","status":"publish","type":"post","link":"http:\/\/classof2023.fountainheadschools.org\/index.php\/2022\/04\/16\/2d-floor-planning\/","title":{"rendered":"2D Floor planning"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">2d floor plan is a flat drawing of the analyzed property, it consists of all the rooms detailing and how the house looks in a flat\/2d dimension, I choose this experience because this is what I like doing and want to pursue it as a future career. the LO\u2019s I want to do for this experience is LO1, LO2, LO3, LO4<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">LO1 (Identify own strengths and develop areas for growth)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">doing this as an experience was very helpful for me because this is something which is i like and want to pursue, my only area of development is I started using AutoCAD by watching basic videos but i couldn\u2019t make anything because it was very complex for me so i had to switch to a less effort source.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">LO2 (Demonstrate that challenges have been undertaken, developing new skills in the process)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">although having prior knowledge, this was my first time creating a very professional 2d floor plan, because I\u2019m very lazy and this work needs consistency of time and attention. it was very challenging for me.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">LO4 (Show commitment to and perseverance in CAS experiences)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">everyday i used to work on making something new for 30-40 minutes to learn a different skill and work on different projects.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-3-1024x576.png\" alt=\"\" class=\"wp-image-5733\" srcset=\"http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-3-1024x576.png 1024w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-3-300x169.png 300w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-3-768x432.png 768w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-3-1536x864.png 1536w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-3.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"507\" src=\"https:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-5-1024x507.png\" alt=\"\" class=\"wp-image-5734\" srcset=\"http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-5-1024x507.png 1024w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-5-300x149.png 300w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-5-768x380.png 768w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-5-1536x761.png 1536w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-5.png 1916w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"535\" src=\"https:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-6-1024x535.png\" alt=\"\" class=\"wp-image-5731\" srcset=\"http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-6-1024x535.png 1024w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-6-300x157.png 300w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-6-768x401.png 768w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-6-1536x802.png 1536w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-6.png 1814w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"763\" src=\"https:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-7-1024x763.png\" alt=\"\" class=\"wp-image-5732\" srcset=\"http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-7-1024x763.png 1024w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-7-300x224.png 300w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-7-768x572.png 768w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-7.png 1256w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"701\" src=\"https:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-8-1024x701.png\" alt=\"\" class=\"wp-image-5730\" srcset=\"http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-8-1024x701.png 1024w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-8-300x205.png 300w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-8-768x526.png 768w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-8.png 1386w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"507\" src=\"https:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-9-1024x507.png\" alt=\"\" class=\"wp-image-5735\" srcset=\"http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-9-1024x507.png 1024w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-9-300x149.png 300w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-9-768x380.png 768w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-9-1536x761.png 1536w, http:\/\/classof2023.fountainheadschools.org\/wp-content\/uploads\/2022\/04\/2022-04-01-9.png 1892w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>2d floor plan is a flat drawing of the analyzed property, it consists of all the rooms detailing and how the house looks in a flat\/2d dimension, I choose this experience because this is what I like doing and want to pursue it as a future career. the LO\u2019s I want to do for this [&hellip;]<\/p>\n","protected":false},"author":94,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5729","post","type-post","status-publish","format-standard","hentry","category-acumen"],"_links":{"self":[{"href":"http:\/\/classof2023.fountainheadschools.org\/index.php\/wp-json\/wp\/v2\/posts\/5729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/classof2023.fountainheadschools.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/classof2023.fountainheadschools.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/classof2023.fountainheadschools.org\/index.php\/wp-json\/wp\/v2\/users\/94"}],"replies":[{"embeddable":true,"href":"http:\/\/classof2023.fountainheadschools.org\/index.php\/wp-json\/wp\/v2\/comments?post=5729"}],"version-history":[{"count":2,"href":"http:\/\/classof2023.fountainheadschools.org\/index.php\/wp-json\/wp\/v2\/posts\/5729\/revisions"}],"predecessor-version":[{"id":6035,"href":"http:\/\/classof2023.fountainheadschools.org\/index.php\/wp-json\/wp\/v2\/posts\/5729\/revisions\/6035"}],"wp:attachment":[{"href":"http:\/\/classof2023.fountainheadschools.org\/index.php\/wp-json\/wp\/v2\/media?parent=5729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/classof2023.fountainheadschools.org\/index.php\/wp-json\/wp\/v2\/categories?post=5729"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/classof2023.fountainheadschools.org\/index.php\/wp-json\/wp\/v2\/tags?post=5729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}